{"id":14292,"date":"2015-09-11T20:11:45","date_gmt":"2015-09-11T18:11:45","guid":{"rendered":"http:\/\/www.palledicuoio.com\/wordpress\/?p=14292"},"modified":"2019-01-03T18:57:47","modified_gmt":"2019-01-03T17:57:47","slug":"italia-basket-europeo-lille-berlino","status":"publish","type":"post","link":"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/","title":{"rendered":"Tutti a Lille per il sogno dell&#8217;Italia del basket (e perch\u00e9 ne parliamo solo ora)"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;<a href=\"http:\/\/sport.sky.it\/sport\/basket\/2015\/09\/01\/italia-12-convocati-pianigiani-europeo.html\">Italia<\/a> \u00e8 agli ottavi del campionato europeo di pallacanestro. Ha fatto le valigie ed \u00e8 partita per Lille dove domenica inizier\u00e0 la fase a eliminazione diretta. E noi non ne abbiamo parlato. Perch\u00e9? <strong>Perch\u00e9 Gavino \u00e8 un idiota sentimentale<\/strong> e avendo giocato tanti anni a basket non \u00e8 riuscito a trovare delle battute decenti per trasformare la gioia in cretinismo di qualit\u00e0. Perch\u00e9 esultava e urlava come un ossesso davanti ai canestri pazzeschi di Gallinari e Belinelli, la difesa insospettabile di Bargnani, gli attributi di Gentile e Aradori&#8230; E diciamocelo: avreste voluto un posto con scritto eeeeee! aaaaaa! siiiiiiii&#8230; ??? Non sarebbe stato molto descrittivo o divertente. E questo, d&#8217;altronde, non \u00e8 un blog erotico. Almeno non ancora.<\/p>\n<p><a href=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/1cd72124ef897b77beb832868f7fc384_169_xl.jpg\"><img loading=\"lazy\" class=\"aligncenter wp-image-14293\" src=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/1cd72124ef897b77beb832868f7fc384_169_xl.jpg\" alt=\"1cd72124ef897b77beb832868f7fc384_169_xl\" width=\"626\" height=\"352\" srcset=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/1cd72124ef897b77beb832868f7fc384_169_xl.jpg 896w, http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/1cd72124ef897b77beb832868f7fc384_169_xl-300x169.jpg 300w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ora per\u00f2 possiamo cercare di ritrovare un minimo di dignit\u00e0 e ritrovare la nostra normale imbecillit\u00e0. Il girone, difficilissimo, \u00e8 un ricordo. <strong>L&#8217;Italia \u00e8 riuscita a superarlo dando prova di avere lo stesso DNA della Nazionale di Myers, Fucka, Meneghin.<\/strong> \u00a0E non importa fino a dove arriver\u00e0. La prima cosa era ritrovare il feeling con i tifosi.<\/p>\n<p style=\"text-align: justify;\">Ora arriva Israele che sta all&#8217;Europa come Babbo Natale sta alla Pasqua. Ma tant&#8217;\u00e8, poteva andarci molto peggio. <strong>Tipo affrontare la Francia di Tony Parker<\/strong>. Si gioca domenica alle 18.30. Ma prima analizziamo e diamo un voto ai protagonisti di questa bella impresa:<\/p>\n<p><a href=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/4c6e60400c7619df0da649e8d44c76a4-kiQF-U10601205099841WtE-700x394@LaStampa.it_.jpg\"><img loading=\"lazy\" class=\"aligncenter wp-image-14294\" src=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/4c6e60400c7619df0da649e8d44c76a4-kiQF-U10601205099841WtE-700x394@LaStampa.it_.jpg\" alt=\"4c6e60400c7619df0da649e8d44c76a4-kiQF-U10601205099841WtE-700x394@LaStampa.it\" width=\"620\" height=\"349\" srcset=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/4c6e60400c7619df0da649e8d44c76a4-kiQF-U10601205099841WtE-700x394@LaStampa.it_.jpg 700w, http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/4c6e60400c7619df0da649e8d44c76a4-kiQF-U10601205099841WtE-700x394@LaStampa.it_-300x169.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>CINCIARINI<\/strong>: Ha appena avuto un figlio. Cincia Junior. Affronta playmaker piccoli, veloci, tecnici, rompiballe. Non fa una piega. Infila i tiri decisivi nonostantegli allenatori avversari continuino a urlare: \u00abQuello che sembra un commesso dell&#8217;Ikea lasciatelo tirare!\u00bb. Voto: Sette e quaranta.<\/p>\n<p style=\"text-align: justify;\"><strong>HACKETT<\/strong>: Ancora poco incisivo. Ma anche poco molare e canino. Fatica ad addentare con continuit\u00e0 la partita e si accende solo a sprazzi. Pu\u00f2 e deve mordere di pi\u00f9. In attacco come in difesa. Voto: S(e)i applica ma potrebbe fare di pi\u00f9.<\/p>\n<p style=\"text-align: justify;\"><strong>BELINELLI<\/strong>: E che gli vuoi dire? Met\u00e0 dei tiri che mette sono presi senza ritmo, in precario equilibrio, su una gamba e mezzo, con le sopracciglia storte e con le simmetrie di un barbone ubriaco. Ma vanno dentro perch\u00e9 il talento \u00e8 cristallino e la voglia di vincere infinita. Voto: 9 e tre quarti.<\/p>\n<p style=\"text-align: justify;\"><strong>GALLINARI<\/strong>: Mai stato cos\u00ec forte. Mai stato cos\u00ec dominante. Mai stato cos\u00ec prepotente. Mai stato cos\u00ec maturo. Mai stato cos\u00ec antisportivato dagli arbitri. Il giocatore pi\u00f9 forte dell&#8217;Europeo. E lo abbiamo noi. A Denver c&#8217;\u00e8 chi ride. A Crotone, La Maddalena, Gorizia e Ventimiglia pure. Voto: 1 milione di biliardi di fantastilioni.<\/p>\n<p style=\"text-align: justify;\"><strong>CUSIN<\/strong>: L&#8217;uomo che ha gli occhi di un Siberian Husky sta dando un contributo alla causa che manco le campagne di crowdfunding pi\u00f9 note potrebbero eguagliare. Ogni tanto concede tiri liberi di troppo agli avversari quando hanno gi\u00e0 schiacciato, sono tornati a terra, hanno guardato il tabellone e poi l&#8217;ora. Ma resta una bella, stupenda sorpresa. Voto: 4765 metri sopra il livello del mare.<\/p>\n<p style=\"text-align: justify;\"><strong>ARADORI<\/strong>: Ogni volta che entra in campo la prima cosa che pensi \u00e8: &#8220;Questo si \u00e8 trombato met\u00e0 delle fidanzare dei giocatori avversari&#8221;. Poi per\u00f2 lo vedi giocare e capisci che \u00e8 capace di metterla in saccoccia a tanti anche sul parquet. Sue sono alcune delle giocate pi\u00f9 belle e significative dell&#8217;Europeo azzurro. Voto: 10 su meetic.<\/p>\n<p style=\"text-align: justify;\"><strong>BARGNANI<\/strong>: Una volta lo chiamavano mago. Poi ha dovuto subire una serie di soprannomi che nessuno di noi avrebbe appioppato al nostro peggior nemico. E invece ha stupito tutti: mani delicate anche senza bacchetta, scivolamenti degni del miglior libro di incantesimi e una faccia giusta. Voto: Oltre Ogni Previsione (secondo i parametri di Hogwarts).<\/p>\n<p style=\"text-align: justify;\"><strong>MELLI<\/strong>: Vedi Hackett. C&#8217;\u00e8 sempre. Lotta. Picchia. Spinge. Difende. Acchiappa. Tira. Ma manca ancora qualcosa per fare il salto di qualit\u00e0. Quello che non solo ti fa prendere il rimbalzo ma ti da il rispetto e il timore degli avversari. Voto: ottanta voglia di fare.<\/p>\n<p style=\"text-align: justify;\"><strong>GENTILE<\/strong>: Si prende la squadra sulle spalle nei momenti di difficolt\u00e0 Bulleggia in area, da fuori, con gli arbitri. \u00c8 talmente maturo che ogni tanto casca in qualche errore o forzatura di troppo. Ma \u00e8 un fenomeno vero. Voto: 22 come gli anni che non dimostra di avere. Almeno in campo.<\/p>\n<p style=\"text-align: justify;\"><strong>DATOME<\/strong>: \u00c8 in panchina fuori uso. Ma la sua voce si sente come se fosse sul parquet e la barba punge anche di pi\u00f9. Capitano non giocatore. E quando capitano certe cose solo i leader sanno farsi sentire cos\u00ec. VOTO: SV (solo voce).<\/p>\n<p style=\"text-align: justify;\"><strong>DELLA VALLE, POLONARA<\/strong>: Sono sempre in piedi. Incoraggiano e tengono uniti i fili dell&#8217;umore di chi va in campo. Ma si sono fatti trovare pronti quando Pianigiani li ha chiamati. Collanti veri. VOTO: SV (super ventenniequalcosadipi\u00f9).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Italia \u00e8 agli ottavi del campionato europeo di pallacanestro. Ha fatto le valigie ed \u00e8 partita per Lille dove domenica&nbsp;[&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":14295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[2131],"jetpack_featured_media_url":"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/ItalBasket.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Lille per il sogno dell&#039;Italia (e perch\u00e9 ne parliamo solo ora)<\/title>\n<meta name=\"description\" content=\"Dopo un girone di ferro l&#039;Italia si riscopre forte e ambiziosa. Ora la fase finale dell&#039;Europeo a Lille. Tocca ad Israele e gli azzurri sono pronti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Lille per il sogno dell&#039;Italia (e perch\u00e9 ne parliamo solo ora)\" \/>\n<meta property=\"og:description\" content=\"Dopo un girone di ferro l&#039;Italia si riscopre forte e ambiziosa. Ora la fase finale dell&#039;Europeo a Lille. Tocca ad Israele e gli azzurri sono pronti.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/\" \/>\n<meta property=\"og:site_name\" content=\"Palle di cuoio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/palledicuoio\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-11T18:11:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-03T17:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/ItalBasket.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@Palledicuoio\" \/>\n<meta name=\"twitter:site\" content=\"@Palledicuoio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#website\",\"url\":\"http:\/\/www.palledicuoio.com\/wordpress\/\",\"name\":\"Palle di cuoio\",\"description\":\"Un format demenzial-sportivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.palledicuoio.com\/wordpress\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2015\/09\/ItalBasket.jpg\",\"width\":640,\"height\":427},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/#webpage\",\"url\":\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/\",\"name\":\"A Lille per il sogno dell'Italia (e perch\\u00e9 ne parliamo solo ora)\",\"isPartOf\":{\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/#primaryimage\"},\"datePublished\":\"2015-09-11T18:11:45+00:00\",\"dateModified\":\"2019-01-03T17:57:47+00:00\",\"author\":{\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#\/schema\/person\/5d8faacc72c7110624daa6e8938abb5e\"},\"description\":\"Dopo un girone di ferro l'Italia si riscopre forte e ambiziosa. Ora la fase finale dell'Europeo a Lille. Tocca ad Israele e gli azzurri sono pronti.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.palledicuoio.com\/wordpress\/italia-basket-europeo-lille-berlino\/\"]}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#\/schema\/person\/5d8faacc72c7110624daa6e8938abb5e\",\"name\":\"Gavino\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/6ddc0a744c962adce47cff51821cca84?s=96&d=retro&r=g\",\"caption\":\"Gavino\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts\/14292"}],"collection":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14292"}],"version-history":[{"count":2,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts\/14292\/revisions"}],"predecessor-version":[{"id":14297,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts\/14292\/revisions\/14297"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/media\/14295"}],"wp:attachment":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14292"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}