{"id":18230,"date":"2017-08-01T17:41:49","date_gmt":"2017-08-01T15:41:49","guid":{"rendered":"http:\/\/www.palledicuoio.com\/wordpress\/?p=18230"},"modified":"2019-06-04T18:48:06","modified_gmt":"2019-06-04T16:48:06","slug":"neymar-psg-qatar-testimonial","status":"publish","type":"post","link":"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/","title":{"rendered":"Le cose che (forse) Neymar dovr\u00e0 fare come testimonial di Qatar 2022"},"content":{"rendered":"<p>Neymar \u00e8 a un passo dal <a href=\"https:\/\/sport.sky.it\/calciomercato\/estero\/2017\/08\/01\/neymar-psg-visite-mediche-dubai-calciomercato-live-barcellona-.html\">PSG<\/a>. Eppure, se l&#8217;affare dovesse andare\u00a0in porto, il cartellino del giocatore brasiliano non sar\u00e0 acquisito dalla squadra francese ma dal Qatar. Come testimonial dei mondiali di calcio del 2022. Tutto questo per pagare una clausola rescissoria enorme, oltre 220 milioni di euro, e aggirare il <a href=\"http:\/\/www.gazzetta.it\/Calciomercato\/25-07-2017\/fair-play-finanziario-com-era-come-puo-cambiare-uefa-210536116773.shtml\">fair play finanziario dell&#8217;UEFA<\/a>. Una roba che manco il pi\u00f9 ubriacone degli sceneggiatori hollywoodiani sarebbe stato in grado di scrivere. E non \u00e8 detto che il malefico piano degli emiri funzioni. Tra minacce di ricorsi del Barcellona e assicurazioni da parte delle istituzioni del calcio europee di controlli e vigilanza. Questione di cavilli e avvocati.<\/p>\n<h2><strong>I compiti di un testimonial<\/strong><\/h2>\n<p>In ogni caso sarebbe etico che Neymar iniziasse a calarsi nei panni del testimonial. Per questo proponiamo alcuni compiti che dovrebbe ricoprire da qui al 2022. Una lista per prepararsi a quello che diventer\u00e0 il suo mestiere principale: la mascotte.<\/p>\n<ul>\n<li>Vestirsi un weekend al mese da &#8220;sultano palleggino&#8221; per girare tutto il Paese come giocoliere del pallone.<\/li>\n<li>Visitare\u00a0tutte le case di Doha insegnando il fuorigioco e le regole della VAR<\/li>\n<li>Imparare a memoria l&#8217;inno del Qatar e, di volta in volta, di tutte le nazioni che si qualificheranno<\/li>\n<li>Aiutare gli operai, sottopagati e vessati, nella costruzione degli stadi testando manti erbosi e palloni (e denunciando gli abusi)<\/li>\n<li>Girare i licei premiando i giovani calciatori e calciatrici qatarioti in tornei creati per l&#8217;occasione<\/li>\n<li>Imparare a memoria la geografia e la storia del Paese<\/li>\n<li>Fare un selfie con tutti i giocatori della nazionale qatariana, sorridendo ogni volta e raccontando la loro storia in un instagram stories<\/li>\n<li>Passare le vacanze estive a Doha. Ogni anno. Rinunciando a Copacabana.<\/li>\n<li>Fare il pendolare prendendo casa in uno dei grattacieli della Capitale del Qatar. Viaggiando ogni giorno verso Parigi.<\/li>\n<li>Costruirsi un harem<\/li>\n<li>Imparare a giocare con la tunica<\/li>\n<li>Comprare l&#8217;ultimo modello di cammello e viaggiare nel deserto portando solo il pallone<\/li>\n<\/ul>\n<p>Insomma. Un testimonial di un evento cos\u00ec grande non pu\u00f2 mica permettersi di assentarsi o di venir meno al suo ruolo. Compatibilmente, ovvio, con gli impegni del PSG. Sei pronto Neymar?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neymar \u00e8 a un passo dal PSG. Eppure, se l&#8217;affare dovesse andare\u00a0in porto, il cartellino del giocatore brasiliano non sar\u00e0&nbsp;[&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18232,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,3],"tags":[],"jetpack_featured_media_url":"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2017\/08\/Brasil_conquista_primeiro_ouro_oli\u0301mpico_no_futebol_1039247-20082016-_mg_3424.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le cose che (forse) Neymar dovr\u00e0 fare come testimonial di Qatar 2022<\/title>\n<meta name=\"description\" content=\"La lista delle cose che il giocatore brasiliano dovr\u00e0 fare una volta che diventer\u00e0 testimoniale di Qatar 2022 (oltre a giocare per il PSG)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le cose che (forse) Neymar dovr\u00e0 fare come testimonial di Qatar 2022\" \/>\n<meta property=\"og:description\" content=\"La lista delle cose che il giocatore brasiliano dovr\u00e0 fare una volta che diventer\u00e0 testimoniale di Qatar 2022 (oltre a giocare per il PSG)\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/\" \/>\n<meta property=\"og:site_name\" content=\"Palle di cuoio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/palledicuoio\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-01T15:41:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-04T16:48:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2017\/08\/Brasil_conquista_primeiro_ouro_oli\u0301mpico_no_futebol_1039247-20082016-_mg_3424-960x640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@Palledicuoio\" \/>\n<meta name=\"twitter:site\" content=\"@Palledicuoio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#website\",\"url\":\"http:\/\/www.palledicuoio.com\/wordpress\/\",\"name\":\"Palle di cuoio\",\"description\":\"Un format demenzial-sportivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.palledicuoio.com\/wordpress\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"http:\/\/www.palledicuoio.com\/wordpress\/wp-content\/uploads\/2017\/08\/Brasil_conquista_primeiro_ouro_oli\\u0301mpico_no_futebol_1039247-20082016-_mg_3424.jpg\",\"width\":3800,\"height\":2533,\"caption\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/#webpage\",\"url\":\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/\",\"name\":\"Le cose che (forse) Neymar dovr\\u00e0 fare come testimonial di Qatar 2022\",\"isPartOf\":{\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/#primaryimage\"},\"datePublished\":\"2017-08-01T15:41:49+00:00\",\"dateModified\":\"2019-06-04T16:48:06+00:00\",\"author\":{\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#\/schema\/person\/5d8faacc72c7110624daa6e8938abb5e\"},\"description\":\"La lista delle cose che il giocatore brasiliano dovr\\u00e0 fare una volta che diventer\\u00e0 testimoniale di Qatar 2022 (oltre a giocare per il PSG)\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.palledicuoio.com\/wordpress\/neymar-psg-qatar-testimonial\/\"]}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#\/schema\/person\/5d8faacc72c7110624daa6e8938abb5e\",\"name\":\"Gavino\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.palledicuoio.com\/wordpress\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/6ddc0a744c962adce47cff51821cca84?s=96&d=retro&r=g\",\"caption\":\"Gavino\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts\/18230"}],"collection":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/comments?post=18230"}],"version-history":[{"count":5,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts\/18230\/revisions"}],"predecessor-version":[{"id":18237,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/posts\/18230\/revisions\/18237"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/media\/18232"}],"wp:attachment":[{"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/media?parent=18230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/categories?post=18230"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.palledicuoio.com\/wordpress\/wp-json\/wp\/v2\/tags?post=18230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}